{"id":35,"date":"2016-10-14T17:23:25","date_gmt":"2016-10-14T15:23:25","guid":{"rendered":"http:\/\/www.ulli.ulrike-leopold.de\/?page_id=35"},"modified":"2021-11-21T16:29:37","modified_gmt":"2021-11-21T15:29:37","slug":"uebermalungen","status":"publish","type":"page","link":"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/","title":{"rendered":"Alles \u00dcbermalungen"},"content":{"rendered":"<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"800\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/malerei-2\\\/uebermalungen\\\/&quot;,&quot;likes_blog_id&quot;:118919282}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 800px; height: 533px;\" data-original-width=\"800\" data-original-height=\"533\" > <div class=\"gallery-group images-1\" style=\"width: 533px; height: 533px;\" data-original-width=\"533\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-13\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"529\"> <meta itemprop=\"height\" content=\"529\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"446\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_14_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_14_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_14_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_14_2008_09.jpg?w=529&#038;h=529&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_14_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_14_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_14_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_14_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"529\" height=\"529\" loading=\"lazy\" data-original-width=\"529\" data-original-height=\"529\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 01 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 529px; height: 529px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 01 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 267px; height: 533px;\" data-original-width=\"267\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-8\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"441\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_9_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_9_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_9_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_9_2008_09.jpg?w=263&#038;h=263&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_9_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_9_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_9_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_9_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"263\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 02 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 263px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 02 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-10\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"262\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"443\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_11_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_11_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_11_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_11_2008_09.jpg?w=263&#038;h=262&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_11_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_11_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_11_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_11_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"262\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"262\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 03 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 262px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 03 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 800px; height: 267px;\" data-original-width=\"800\" data-original-height=\"267\" > <div class=\"gallery-group images-1\" style=\"width: 267px; height: 267px;\" data-original-width=\"267\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-17\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"450\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_18_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_18_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_18_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_18_2008_09.jpg?w=263&#038;h=263&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_18_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_18_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_18_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_18_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"263\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 04 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 263px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 04 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 267px; height: 267px;\" data-original-width=\"267\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"435\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_3_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_3_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_3_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_3_2008_09.jpg?w=263&#038;h=263&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_3_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_3_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_3_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_3_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"263\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 05 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 263px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 05 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 266px; height: 267px;\" data-original-width=\"266\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-14\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"262\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"447\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_15_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_15_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_15_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_15_2008_09.jpg?w=262&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_15_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_15_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_15_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_15_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"262\" height=\"263\" loading=\"lazy\" data-original-width=\"262\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 06 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 262px; height: 263px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 06 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 800px; height: 533px;\" data-original-width=\"800\" data-original-height=\"533\" > <div class=\"gallery-group images-2\" style=\"width: 267px; height: 533px;\" data-original-width=\"267\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-15\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"448\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_16_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_16_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_16_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_16_2008_09.jpg?w=263&#038;h=263&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_16_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_16_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_16_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_16_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"263\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 07 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 263px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 07 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"262\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"434\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_2_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_2_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_2_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_2_2008_09.jpg?w=263&#038;h=262&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_2_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_2_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_2_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_2_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"262\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"262\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 08 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 262px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 08 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 533px; height: 533px;\" data-original-width=\"533\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-12\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"529\"> <meta itemprop=\"height\" content=\"529\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"445\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_13_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_13_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_13_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_13_2008_09.jpg?w=529&#038;h=529&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_13_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_13_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_13_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_13_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"529\" height=\"529\" loading=\"lazy\" data-original-width=\"529\" data-original-height=\"529\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 09 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 529px; height: 529px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 09 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 800px; height: 400px;\" data-original-width=\"800\" data-original-height=\"400\" > <div class=\"gallery-group images-1\" style=\"width: 400px; height: 400px;\" data-original-width=\"400\" data-original-height=\"400\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-7\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"396\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"440\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_8_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_8_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_8_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_8_2008_09.jpg?w=396&#038;h=396&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_8_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_8_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_8_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_8_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"396\" height=\"396\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"396\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 10 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 396px; height: 396px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 10 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 400px; height: 400px;\" data-original-width=\"400\" data-original-height=\"400\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-16\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"396\"> <meta itemprop=\"height\" content=\"396\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"449\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_17_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_17_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_17_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_17_2008_09.jpg?w=396&#038;h=396&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_17_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_17_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_17_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_17_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"396\" height=\"396\" loading=\"lazy\" data-original-width=\"396\" data-original-height=\"396\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 11 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 396px; height: 396px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 11 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 800px; height: 533px;\" data-original-width=\"800\" data-original-height=\"533\" > <div class=\"gallery-group images-1\" style=\"width: 533px; height: 533px;\" data-original-width=\"533\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-4\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"529\"> <meta itemprop=\"height\" content=\"529\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"437\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_5_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_5_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_5_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_5_2008_09.jpg?w=529&#038;h=529&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_5_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_5_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_5_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_5_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"529\" height=\"529\" loading=\"lazy\" data-original-width=\"529\" data-original-height=\"529\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 12 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 529px; height: 529px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 12 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 267px; height: 533px;\" data-original-width=\"267\" data-original-height=\"533\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-5\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"438\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_6_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_6_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_6_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_6_2008_09.jpg?w=263&#038;h=263&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_6_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_6_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_6_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_6_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"263\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 13 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 263px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 13 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-6\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"262\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"439\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_7_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_7_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_7_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_7_2008_09.jpg?w=263&#038;h=262&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_7_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_7_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_7_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_7_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"262\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"262\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 14 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 262px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 14 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 800px; height: 267px;\" data-original-width=\"800\" data-original-height=\"267\" > <div class=\"gallery-group images-1\" style=\"width: 267px; height: 267px;\" data-original-width=\"267\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-11\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"444\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_12_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_12_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_12_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_12_2008_09.jpg?w=263&#038;h=263&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_12_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_12_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_12_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_12_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"263\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 15 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 263px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 15 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 267px; height: 267px;\" data-original-width=\"267\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-9\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"263\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"442\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_10_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_10_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_10_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_10_2008_09.jpg?w=263&#038;h=263&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_10_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_10_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_10_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_10_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"263\" height=\"263\" loading=\"lazy\" data-original-width=\"263\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 16 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 263px; height: 263px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 16 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 266px; height: 267px;\" data-original-width=\"266\" data-original-height=\"267\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/serie-menschlich-bewegt-200809-20-x-20-cm-mischtechnik-auf-laserdruck-18\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"262\"> <meta itemprop=\"height\" content=\"263\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"451\" data-orig-file=\"https:\/\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg\" data-orig-size=\"800,800\" data-comments-opened=\"\" data-image-title=\"\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg?fit=800%2C800&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg?w=262&#038;h=263&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg?resize=768%2C768&amp;ssl=1 768w\" width=\"262\" height=\"263\" loading=\"lazy\" data-original-width=\"262\" data-original-height=\"263\" itemprop=\"http:\/\/schema.org\/image\" title=\"\" alt=\"Serie &#039;Menschlich bewegt&#039; 17 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck\" style=\"width: 262px; height: 263px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Serie &#8218;Menschlich bewegt&#8216; 17 | 2008\/09 | 20 x 20 cm | Mischtechnik auf Laserdruck <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":25,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[23,27],"tags":[],"class_list":["post-35","page","type-page","status-publish","hentry","category-alles-nur-ein-spiel","category-malerei"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alles \u00dcbermalungen - Ulrike Leopold<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alles \u00dcbermalungen - Ulrike Leopold\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ulrike Leopold\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-21T15:29:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg?w=529&#038;h=529&#038;crop=1&#038;ssl=1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/malerei-2\\\/uebermalungen\\\/\",\"url\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/malerei-2\\\/uebermalungen\\\/\",\"name\":\"Alles \u00dcbermalungen - Ulrike Leopold\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/#website\"},\"datePublished\":\"2016-10-14T15:23:25+00:00\",\"dateModified\":\"2021-11-21T15:29:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/malerei-2\\\/uebermalungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/malerei-2\\\/uebermalungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/malerei-2\\\/uebermalungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Malerei\",\"item\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/malerei-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alles \u00dcbermalungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/\",\"name\":\"Ulrike Leopold\",\"description\":\"Malerei und Zeichnung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/#\\\/schema\\\/person\\\/1bb05548ef8c3706b3ed43a49d201731\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.ulrike-leopold.de\\\/home\\\/#\\\/schema\\\/person\\\/1bb05548ef8c3706b3ed43a49d201731\",\"name\":\"ulli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/11a80f167712a54e0708205c339a2e8a1703d5d003aeb30a0e5a540844b892a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/11a80f167712a54e0708205c339a2e8a1703d5d003aeb30a0e5a540844b892a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/11a80f167712a54e0708205c339a2e8a1703d5d003aeb30a0e5a540844b892a9?s=96&d=mm&r=g\",\"caption\":\"ulli\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/11a80f167712a54e0708205c339a2e8a1703d5d003aeb30a0e5a540844b892a9?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alles \u00dcbermalungen - Ulrike Leopold","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/","og_locale":"de_DE","og_type":"article","og_title":"Alles \u00dcbermalungen - Ulrike Leopold","og_url":"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/","og_site_name":"Ulrike Leopold","article_modified_time":"2021-11-21T15:29:37+00:00","og_image":[{"url":"https:\/\/i0.wp.com\/www.ulrike-leopold.de\/wp-content\/uploads\/2016\/10\/Serie-Menschlich-bewegt_I_2008_09.jpg?w=529&#038;h=529&#038;crop=1&#038;ssl=1","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/","url":"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/","name":"Alles \u00dcbermalungen - Ulrike Leopold","isPartOf":{"@id":"https:\/\/www.ulrike-leopold.de\/home\/#website"},"datePublished":"2016-10-14T15:23:25+00:00","dateModified":"2021-11-21T15:29:37+00:00","breadcrumb":{"@id":"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/uebermalungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ulrike-leopold.de\/home\/"},{"@type":"ListItem","position":2,"name":"Malerei","item":"https:\/\/www.ulrike-leopold.de\/home\/malerei-2\/"},{"@type":"ListItem","position":3,"name":"Alles \u00dcbermalungen"}]},{"@type":"WebSite","@id":"https:\/\/www.ulrike-leopold.de\/home\/#website","url":"https:\/\/www.ulrike-leopold.de\/home\/","name":"Ulrike Leopold","description":"Malerei und Zeichnung","publisher":{"@id":"https:\/\/www.ulrike-leopold.de\/home\/#\/schema\/person\/1bb05548ef8c3706b3ed43a49d201731"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ulrike-leopold.de\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.ulrike-leopold.de\/home\/#\/schema\/person\/1bb05548ef8c3706b3ed43a49d201731","name":"ulli","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/11a80f167712a54e0708205c339a2e8a1703d5d003aeb30a0e5a540844b892a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/11a80f167712a54e0708205c339a2e8a1703d5d003aeb30a0e5a540844b892a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11a80f167712a54e0708205c339a2e8a1703d5d003aeb30a0e5a540844b892a9?s=96&d=mm&r=g","caption":"ulli"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/11a80f167712a54e0708205c339a2e8a1703d5d003aeb30a0e5a540844b892a9?s=96&d=mm&r=g"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/pages\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":19,"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/pages\/35\/revisions"}],"predecessor-version":[{"id":1758,"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/pages\/35\/revisions\/1758"}],"up":[{"embeddable":true,"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/pages\/25"}],"wp:attachment":[{"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/media?parent=35"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/categories?post=35"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ulrike-leopold.de\/home\/wp-json\/wp\/v2\/tags?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}